{"id":521,"date":"2018-09-16T15:35:58","date_gmt":"2018-09-16T13:35:58","guid":{"rendered":"http:\/\/petra-bartoli.de\/?p=521"},"modified":"2018-05-14T12:50:04","modified_gmt":"2018-05-14T10:50:04","slug":"autorinnen-schreiben-nicht-nur-sie-lesen-auch","status":"publish","type":"post","link":"https:\/\/petra-bartoli.de\/index.php\/autorinnen-schreiben-nicht-nur-sie-lesen-auch\/","title":{"rendered":"Autor*innen schreiben nicht nur, sie lesen auch&#8230;"},"content":{"rendered":"<p>Ich bin sehr stolz darauf, dass meine B\u00fccher zu den Lieblingsb\u00fcchern von Leserinnen und Lesern geh\u00f6ren. Aber selbstverst\u00e4ndlich schreiben ich nicht nur Geschichten, sondern lese auch leidenschaftlich gerne. Vielleicht fragt Ihr Euch jetzt: Und was liest eine Autorin dann so?<\/p>\n<p>Ich verrate Euch heute meine zehn Lieblingsb\u00fccher, die mich entweder ganz aktuell begleiten, ber\u00fchren und begeistern, oder schon mein Leben lange inspirierendes Lesefutter f\u00fcr mich sind:<\/p>\n<ol>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/104829996?partner=petra-bartoli\">Pippi Langstrumpf<\/a> (Astrid Lindgren, Oetinger, 1970)\u2013 ein Klassiker, der mich schon beinahe ein Leben lang begleitet. Ich glaube, dar\u00fcber muss ich gar keine Worte verlieren&#8230;<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/10128886?partner=petra-bartoli\">In meinen Tr\u00e4umen l\u00e4utet es Sturm<\/a> (Mascha Kal\u00e9ko, dtv, 1978): Ich lese nicht nur gerne Belletristik, sondern auch Lyrik. Und Mascha Kal\u00e9ko ist eine echte Herzenslyrikerin f\u00fcr mich!<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/102352423?partner=petra-bartoli\">Der Chronist der Winde<\/a> (Henning Mankell, dtv, 2002): Ich mag die meisten B\u00fccher von Mankell. Dieses hat mich ganz besonders ber\u00fchrt \u2013 vielleicht weil ich selbst Mosambik schon einmal bereist und eine intensive Verbindung zu diesem Land habe. Ich mag aber auch Mankells Thriller. Was ich an Mankell au\u00dfer seiner Literatur noch sehr sch\u00e4tze: Er hat ein SOS-Kinderdorf in Mosambik finanziert und in Maputo, der Hauptstadt von Mosambik ein Theater aufgebaut. Wow!<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/1012293832?partner=petra-bartoli\">Ein fabelhafter L\u00fcgner<\/a> (Susann P\u00e1sztor, KiWi, 2010): Die Geschichte erz\u00e4hlt das Leben von Joshi Moln\u00e1r aus der Perspektive seiner jugendlichen Enkeltochter. Nicht nur dieses Buch, auch die beiden weiteren Romane der Autorin haben mich begeistert!<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/107591236?partner=petra-bartoli\">Schneewittchen muss sterben<\/a> (Nele Neuhaus, List, 2010): Ich liebe Krimis und Thriller. Vielleicht weil sie ein gutes Gegenst\u00fcck sind zur Kinderliteratur, die ich selbst schreibe. Besonders gerne lese ich Nele Neuhaus. Dieser Band rund um das Ermittlerteam Pia Kirchhoff und Oliver von Bodenstein ist einer meiner Lieblingskrimis.<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/1021908849?partner=petra-bartoli\">28 Tage lang<\/a> (David Safier, Kindler, 2014): Ich wei\u00df noch, dass dieses Buch erst lange im Regal stand, bevor ich es schlie\u00dflich gelesen habe. Die Geschichte spielt im Warschauer Ghetto und ist keine leichte Kost. Aber \u00e4u\u00dferst lesenswert!<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/1022454340?partner=petra-bartoli\">Der Club der Traumt\u00e4nzer<\/a> (Andreas Izquierdo, Dumont, 2015): Wie wird ein Schn\u00f6sel zum mitf\u00fchlenden Menschen? Dieser Frage spielt in der Geschichte die Hauptrolle. Was mir sehr an dem Roman gef\u00e4llt: Andreas Izquierdo l\u00e4sst benachteiligte Kinder mitspielen \u2013 gut gezeichnet, authentisch und ohne Klischee. Hervorragend!<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/1029634186?partner=petra-bartoli\">Der Pfau<\/a> (Isabel Bogdan, Kipenheuer &amp; Witsch, 2016): Ein kleines, feines Buch \u00fcber eine Tagung in einem Cottage, die aus dem Ruder l\u00e4uft. Wer englischen Humor mag, wird dieses Buch lieben.<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/1024609417?partner=petra-bartoli\">Die Wunder\u00fcbung<\/a> (Daniel Glattauer, Goldmann, 2016): Ich liebe die Geschichten von Daniel Glattauer! Und dieses ganz besonders. Denn es ist ein Theaterst\u00fcck, dass in \u00e4u\u00dferst humorvoller Weise eine Ehetherapie schildert. \u00dcberraschungen inbegriffen.<\/li>\n<li><a href=\"https:\/\/www.buch7.de\/store\/product_details\/1029648331?partner=petra-bartoli\">Unterleuten<\/a> (Juli Zeh, btb, 2017): Diese Buch hat zurecht viel Lob bekommen. Ich bin von der Sprache Juli Zehs begeistert, habe mir S\u00e4tze aus dem Buch auf der Zunge zergehen lassen und war fasziniert davon, wie die Autorin die Geschichte vorantreibt. Ein echtes literarisches Feuerwerk!<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich bin sehr stolz darauf, dass meine B\u00fccher zu den Lieblingsb\u00fcchern von Leserinnen und Lesern geh\u00f6ren. Aber selbstverst\u00e4ndlich schreiben ich nicht nur Geschichten, sondern lese auch leidenschaftlich gerne. Vielleicht fragt Ihr Euch jetzt: Und was liest eine Autorin dann so? Ich verrate Euch heute meine zehn Lieblingsb\u00fccher, die mich entweder ganz aktuell begleiten, ber\u00fchren und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":254,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,4],"tags":[],"class_list":["post-521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-10-jahre-petra-bartoli-y-eckert","category-ueber-mich"],"_links":{"self":[{"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/posts\/521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/comments?post=521"}],"version-history":[{"count":4,"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/posts\/521\/revisions"}],"predecessor-version":[{"id":531,"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/posts\/521\/revisions\/531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/media\/254"}],"wp:attachment":[{"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/media?parent=521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/categories?post=521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/petra-bartoli.de\/index.php\/wp-json\/wp\/v2\/tags?post=521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}